{"id":480327,"date":"2025-04-07T16:53:00","date_gmt":"2025-04-07T14:53:00","guid":{"rendered":"https:\/\/lucacastelli.com\/prodotto\/crazy-montee-par-traction\/"},"modified":"2026-05-18T00:56:22","modified_gmt":"2026-05-17T22:56:22","slug":"crazy-montee-par-traction","status":"publish","type":"product","link":"https:\/\/lucacastelli.com\/fr\/produit\/crazy-montee-par-traction\/","title":{"rendered":"CRAZY PULL ASCENT"},"content":{"rendered":"<p>Affrontez vos aventures en plein air avec notre nouvelle couche interm\u00e9diaire \u00e0 demi-zip, caract\u00e9ris\u00e9e par un style incroyable qui s&#8217;harmonise parfaitement avec les diff\u00e9rentes familles de la collection. Elle repr\u00e9sente la deuxi\u00e8me couche technique parfaite pour les journ\u00e9es les plus froides.<br \/>\nLe Pull Ascent est enti\u00e8rement r\u00e9alis\u00e9 en tissu High Performance, notre tissu phare pour combiner respirabilit\u00e9 et r\u00e9tention de la chaleur dans les couches interm\u00e9diaires.<br \/>\nLe design moderne et color\u00e9 est enrichi de coutures plates contrast\u00e9es et d&#8217;une poche int\u00e9rieure pratique pour DVA. <\/p>\n<p>\u2022 Pull \u00e0 demi-zip et col montant ajust\u00e9<br \/>\n\u2022 Poche poitrine avec zip coll\u00e9e<br \/>\n\u2022 Logos r\u00e9fl\u00e9chissants<br \/>\n\u2022 Coutures plates en couleur contrast\u00e9e<br \/>\n\u2022 Poche int\u00e9rieure pour d\u00e9tecteur de victimes d&#8217;avalanche (DVA)<\/p>\n<p>POIDS : 305 g<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Affrontez vos aventures en plein air avec notre nouvelle couche interm\u00e9diaire \u00e0 demi-zip, caract\u00e9ris\u00e9e par un style incroyable qui s&#8217;harmonise<\/p>\n","protected":false},"featured_media":404539,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"product_brand":[3616],"product_cat":[81,981,982],"product_tag":[],"class_list":{"0":"post-480327","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-crazy-fr","7":"product_cat-vetements","8":"product_cat-vetements-de-loisirs","9":"product_cat-vetements-pour-hommes","10":"sws-gruppo-no-gruppo","11":"sws-conto-ricavi-merci-rivendita-abbigliamento-en","12":"sws-gruppo-iva-iva81-en","14":"first","15":"instock","16":"sale","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product\/480327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/media\/404539"}],"wp:attachment":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/media?parent=480327"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_brand?post=480327"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_cat?post=480327"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_tag?post=480327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}