{"id":464081,"date":"2026-06-03T18:54:33","date_gmt":"2026-06-03T16:54:33","guid":{"rendered":"https:\/\/lucacastelli.com\/prodotto\/ar-3000-l-kit-avec-adaptateur-ap-et-cable-de-connexion\/"},"modified":"2026-06-05T10:39:54","modified_gmt":"2026-06-05T08:39:54","slug":"ar-3000-l-kit-avec-adaptateur-ap-et-cable-de-connexion","status":"publish","type":"product","link":"https:\/\/lucacastelli.com\/fr\/produit\/ar-3000-l-kit-avec-adaptateur-ap-et-cable-de-connexion\/","title":{"rendered":"STIHL AR 3000 L, kit avec adaptateur AP et c\u00e2ble de raccordement"},"content":{"rendered":"<p>Batteries \u00e0 dos lithium-ion \u00e0 haute capacit\u00e9 \u00e9nerg\u00e9tique pour des travaux particuli\u00e8rement longs ; port USB, interface Bluetooth\u00ae pour la connexion \u00e0 STIHL connected. Bo\u00eetier robuste avec poign\u00e9e de transport int\u00e9gr\u00e9e et indicateur de charge (six LED). Contact direct avec la RMA 765 V. En combinaison avec le syst\u00e8me de portage AR L et le c\u00e2ble de raccordement AR L, elles conviennent aux appareils dot\u00e9s d\u2019une prise et, en combinaison avec l\u2019adaptateur AP, elles conviennent aux appareils dot\u00e9s d\u2019un logement pour batterie. Utilisables sous la pluie.<br \/>\n886661951628   <\/p>\n<p>Technologie de cellules de batterie LITHIUM-ION<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AR 3000 L, kit avec adaptateur AP et c\u00e2ble de raccordement<\/p>\n","protected":false},"featured_media":849851,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"product_brand":[3555],"product_cat":[167,1450],"product_tag":[3267],"class_list":{"0":"post-464081","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-stihl-fr","7":"product_cat-machines","8":"product_cat-systemes-de-batteries-accessoires","9":"product_tag-import-stihl-fr","10":"sws-gruppo-macchinari","11":"sws-conto-ricavi-merci-rivendita-macchinari","12":"sws-gruppo-iva-iva81","14":"first","15":"onbackorder","16":"sale","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product\/464081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/media\/849851"}],"wp:attachment":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/media?parent=464081"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_brand?post=464081"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_cat?post=464081"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_tag?post=464081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}