{"id":414971,"date":"2025-04-07T16:53:00","date_gmt":"2025-04-07T14:53:00","guid":{"rendered":"https:\/\/lucacastelli.com\/prodotto\/crazy-gilet-channel-femme\/"},"modified":"2026-09-01T02:18:58","modified_gmt":"2026-09-01T00:18:58","slug":"crazy-gilet-channel-femme","status":"publish","type":"product","link":"https:\/\/lucacastelli.com\/fr\/produit\/crazy-gilet-channel-femme\/","title":{"rendered":"GILET CRAZY CHANNEL WOMAN"},"content":{"rendered":"<p>Gilet hybride avec une isolation l\u00e9g\u00e8re, parfait pour offrir une protection et une chaleur suppl\u00e9mentaires pendant les activit\u00e9s, sans limiter la libert\u00e9 de mouvement.<br \/>\nLe buste, plus expos\u00e9 aux intemp\u00e9ries, est r\u00e9alis\u00e9 avec le nylon innovant I-Tube Channel, sans coutures pour une meilleure performance, tandis que l\u2019ourlet arri\u00e8re et les aisselles sont en Vuelta, un polaire de fabrication italienne chaud, confortable et respirant.<br \/>\nLe v\u00eatement est renforc\u00e9 avec le tissu Two-Face, r\u00e9sistant, respirant et bi-\u00e9lastique, utilis\u00e9 sur les \u00e9paules et sur la partie centrale du dos.<br \/>\nL\u2019embourrage est en Microrollo, un garnissage de fabrication italienne aux qualit\u00e9s similaires au duvet naturel, offrant les m\u00eames avantages mais avec un tissu synth\u00e9tique qui s\u00e8che plus rapidement.<\/p>\n<p>\u2022 Col haut protecteur<br \/>\n\u2022 Zip int\u00e9grale sur le devant<br \/>\n\u2022 Poches pour les mains avec zip<br \/>\n\u2022 Logos r\u00e9fl\u00e9chissants<br \/>\n\u2022 Coutures plates contrast\u00e9es<br \/>\n\u2022 Isolation en microrollo<br \/>\n\u2022 Bas et panneaux en Vuelta respirant, made in Italy<\/p>\n<p>POIDS : 192 g<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gilet hybride avec une isolation l\u00e9g\u00e8re, parfait pour offrir une protection et une chaleur suppl\u00e9mentaires pendant les activit\u00e9s, sans limiter<\/p>\n","protected":false},"featured_media":404024,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"product_brand":[3616],"product_cat":[81,981,1387],"product_tag":[],"class_list":{"0":"post-414971","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-crazy-fr","7":"product_cat-vetements","8":"product_cat-vetements-de-loisirs","9":"product_cat-vetements-pour-femmes","10":"sws-gruppo-no-gruppo","11":"sws-conto-ricavi-merci-rivendita-abbigliamento-en","12":"sws-gruppo-iva-iva81-en","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product\/414971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/media\/404024"}],"wp:attachment":[{"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/media?parent=414971"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_brand?post=414971"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_cat?post=414971"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lucacastelli.com\/fr\/wp-json\/wp\/v2\/product_tag?post=414971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}