{"id":479532,"date":"2025-04-07T16:53:00","date_gmt":"2025-04-07T14:53:00","guid":{"rendered":"https:\/\/lucacastelli.com\/prodotto\/crazy-pant-joker\/"},"modified":"2026-09-01T02:18:46","modified_gmt":"2026-09-01T00:18:46","slug":"crazy-pant-joker","status":"publish","type":"product","link":"https:\/\/lucacastelli.com\/de\/produkt\/crazy-pant-joker\/","title":{"rendered":"CRAZY PANT JOKER"},"content":{"rendered":"<p>Bequeme Hose f\u00fcr die Stadt, die Freizeit und sogar zum Sportklettern geeignet. Diese Hose ist eine der Ikonen der Lifestyle-Kollektion von Crazy. Der jugendliche Schnitt und die stets modischen Farben sind die Erfolgsgeheimnisse dieses ikonischen Modells.<br \/>\nJe nach Farbvariante aus verschiedenen Stoffen gefertigt; von Performance-Baumwolle \u00fcber Denim bis hin zu warmem Samt.  <\/p>\n<p>\u2022 Bequemer elastischer Bund mit verstellbarem Kordelzug<br \/>\n\u2022 Zwei grosse Vordertaschen und eine Ges\u00e4sstasche<br \/>\n\u2022 Verstellbarer elastischer Kordelzug am Beinabschluss<\/p>\n<p>GEWICHT: 504 g<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bequeme Hose f\u00fcr die Stadt, die Freizeit und sogar zum Sportklettern geeignet. Diese Hose ist eine der Ikonen der Lifestyle-Kollektion<\/p>\n","protected":false},"featured_media":404821,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"product_brand":[3614],"product_cat":[82,974,975],"product_tag":[],"class_list":{"0":"post-479532","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-crazy-de","7":"product_cat-kleidung","8":"product_cat-freizeitkleidung","9":"product_cat-herrenbekleidung","10":"sws-gruppo-no-gruppo","11":"sws-conto-ricavi-merci-rivendita-abbigliamento-en","12":"sws-gruppo-iva-iva81-en","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product\/479532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/media\/404821"}],"wp:attachment":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/media?parent=479532"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product_brand?post=479532"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product_cat?post=479532"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product_tag?post=479532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}