{"id":479477,"date":"2025-04-07T16:53:00","date_gmt":"2025-04-07T14:53:00","guid":{"rendered":"https:\/\/lucacastelli.com\/prodotto\/crazy-pant-nach\/"},"modified":"2026-09-01T02:18:45","modified_gmt":"2026-09-01T00:18:45","slug":"crazy-pant-nach","status":"publish","type":"product","link":"https:\/\/lucacastelli.com\/de\/produkt\/crazy-pant-nach\/","title":{"rendered":"CRAZY PANT AFTER"},"content":{"rendered":"<p>Die After PANT wird in der Freizeit, bei Spazierg\u00e4ngen und auch bei Stadtausfl\u00fcgen getragen, aber viele Kletterbegeisterte nutzen sie dank ihres Komforts und ihrer Leichtigkeit zum Klettern, sowohl im Freien als auch in der Halle.<br \/>\nSie ist je nach Farbvariante aus verschiedenen Stoffen gefertigt, die von strapazierf\u00e4higer Stretch-Baumwolle \u00fcber Denim bis hin zu warmem Samt reichen.<\/p>\n<p>\u2022 Komfortabler hoher Bund, bequem auch beim Tragen eines Klettergurts<br \/>\n\u2022 Verstellbare Beinabschl\u00fcsse mit elastischem Kordelzug<br \/>\n\u2022 Passform und Komfort f\u00fcr die Freizeit<br \/>\n\u2022 Mit Stickmotiven verzierte Taschen<\/p>\n<p>GEWICHT: 420 g<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die After PANT wird in der Freizeit, bei Spazierg\u00e4ngen und auch bei Stadtausfl\u00fcgen getragen, aber viele Kletterbegeisterte nutzen sie dank<\/p>\n","protected":false},"featured_media":404775,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"product_brand":[3614],"product_cat":[82,974,1388],"product_tag":[],"class_list":{"0":"post-479477","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-crazy-de","7":"product_cat-kleidung","8":"product_cat-freizeitkleidung","9":"product_cat-damenbekleidung","10":"sws-gruppo-no-gruppo","11":"sws-conto-ricavi-merci-rivendita-abbigliamento-en","12":"sws-gruppo-iva-iva81-en","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product\/479477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/media\/404775"}],"wp:attachment":[{"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/media?parent=479477"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product_brand?post=479477"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product_cat?post=479477"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lucacastelli.com\/de\/wp-json\/wp\/v2\/product_tag?post=479477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}